{"id":3539,"date":"2020-07-25T17:43:56","date_gmt":"2020-07-25T09:43:56","guid":{"rendered":"https:\/\/isdmeditech.com\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/"},"modified":"2024-12-02T14:53:03","modified_gmt":"2024-12-02T06:53:03","slug":"%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9","status":"publish","type":"page","link":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/","title":{"rendered":"\u0645\u0639\u0642\u0645 \u0627\u0644\u064a\u062f\u064a\u0646 _ \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u0629"},"content":{"rendered":"\n\t<div id=\"gap-464610069\" class=\"gap-element clearfix hide-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style scope=\"scope\">\n\n#gap-464610069 {\n  padding-top: 38px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h1 style=\"text-align: center;\">\u0645\u064f\u0635\u0646\u0651\u0639 \u0645\u0639\u0642\u0645 \u0627\u0644\u064a\u062f\u064a\u0646 \u0644 \u062e\u0628\u0631\u0629 10 \u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0644 \u0645\u0633\u062c\u0644 \u0644\u062f\u0649 \u0648\u0632\u0627\u0631\u0629 \u0627\u0644\u0635\u062d\u0629<\/h1>\n<div class=\"slider-wrapper relative\" id=\"slider-747876083\" style=\"background-color:rgb(255,255,255);\">\n    <div class=\"slider slider-nav-circle slider-nav-normal slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": true,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover\" id=\"banner-1979833164\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style scope=\"scope\">\n\n#banner-1979833164 {\n  padding-top: 32%;\n}\n#banner-1979833164 .bg.bg-loaded {\n  background-image: url(https:\/\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1500X500-R1B.jpg);\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n     <style scope=\"scope\">\n             <\/style>\n<\/div>\n\n\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>\u0645\u0639\u0642\u0645 \u0644\u0644\u064a\u062f\u064a\u0646 \u0645\u0646 \u0641\u0626\u0629 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u064a\u0627\u062a. \u0627\u0644\u062a\u0648\u0635\u064a\u0644 \u0645\u0646 \u0627\u0644\u0628\u0627\u0628 \u0625\u0644\u0649 \u0627\u0644\u0628\u0627\u0628 \u0645\u062c\u0627\u0646\u064b\u0627 \u0625\u0644\u0649 \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u0629 \u0639\u0646\u062f \u0627\u0644\u0634\u0631\u0627\u0621 \u0628\u0642\u064a\u0645\u0629 \u062a\u0632\u064a\u062f \u0639\u0646 1500 \u062f\u0648\u0644\u0627\u0631 \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u064a   <\/strong>\u0623\u0648 100 \u062f\u0648\u0644\u0627\u0631 \u0623\u0645\u0631\u064a\u0643\u064a<\/span><\/p>\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"color:rgb(43, 42, 239);\"><i class=\"icon-angle-down\" ><\/i>\u0645\u0639\u0642\u0645 \u0627\u0644\u064a\u062f\u064a\u0646<\/span><b><\/b><\/h2><\/div>\n\n<div class=\"row\"  id=\"row-323693698\">\n\n\n\t<div class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<ul>\n<li><span style=\"color: #000000;\">\u062a\u0645 \u0627\u062e\u062a\u0628\u0627\u0631\u0647\u0627 \u0645\u0639\u0645\u0644\u064a\u064b\u0627 \u0648\u062b\u0628\u062a \u0623\u0646\u0647\u0627 \u062a\u0642\u062a\u0644 99.99% \u0645\u0646 \u0627\u0644\u062c\u0631\u0627\u062b\u064a\u0645 \u0639\u0644\u0649 \u0627\u0644\u0641\u0648\u0631.<\/span><\/li>\n<li><span style=\"color: #000000;\">70\u066a &#8211; 75\u066a \u062a\u0631\u0643\u064a\u0632 \u0627\u0644\u0643\u062d\u0648\u0644 70\u066a &#8211; 75<\/span><\/li>\n<li><span style=\"color: #000000;\">\u063a\u064a\u0631 \u0644\u0632\u062c\u0629 \u0648\u0644\u0637\u064a\u0641\u0629 \u0639\u0644\u0649 \u0627\u0644\u0628\u0634\u0631\u0629<\/span><\/li>\n<li><span style=\"color: #000000;\">\u0634\u0647\u0627\u062f\u0629 \u0627\u0644\u062d\u0644\u0627\u0644*<\/span><\/li>\n<li><span style=\"color: #000000;\">\u062a\u0631\u0643\u064a\u0628\u0629 \u0645\u0633\u062c\u0644\u0629 \u0644\u062f\u0649 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u063a\u0630\u0627\u0621 \u0648\u0627\u0644\u062f\u0648\u0627\u0621 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a\u0629<\/span><\/li>\n<li><span style=\"color: #000000;\">\u0648\u0632\u0627\u0631\u0629 \u0627\u0644\u0635\u062d\u0629 \u0627\u0644\u0645\u0627\u0644\u064a\u0632\u064a\u0629 \u0627\u0644\u0645\u0633\u062c\u0644\u0629 \u0641\u064a \u0645\u0627\u0644\u064a\u0632\u064a\u0627<\/span><\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<ul>\n<li><span style=\"color: #000000;\">\u0627\u0644\u0627\u0645\u062a\u062b\u0627\u0644 \u0644\u0625\u0631\u0634\u0627\u062f\u0627\u062a \u0645\u0646\u0638\u0645\u0629 \u0627\u0644\u0635\u062d\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0648\u0645\u0631\u0627\u0643\u0632 \u0645\u0643\u0627\u0641\u062d\u0629 \u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0648\u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646\u0647\u0627<\/span><\/li>\n<li><span style=\"color: #000000;\">\u0642\u062f\u0631\u0627\u062a \u0635\u0627\u0646\u0639 \u0627\u0644\u0645\u0639\u062f\u0627\u062a \u0627\u0644\u0623\u0635\u0644\u064a\u0629<\/span><\/li>\n<li><span style=\"color: #000000;\">\u0631\u0633\u0648\u0645 \u0627\u0644\u062a\u0648\u0635\u064a\u0644 100 \u062f\u0648\u0644\u0627\u0631 \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u064a \u0644\u0644\u0634\u0631\u0627\u0621 \u0628\u0642\u064a\u0645\u0629 \u0623\u0642\u0644 \u0645\u0646 1500 \u062f\u0648\u0644\u0627\u0631 \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u064a.<\/span><\/li>\n<\/ul>\n<a href=\"#contact_form_sg_id\" target=\"_self\" class=\"button alert box-shadow-4 box-shadow-5-hover lowercase expand\"  style=\"border-radius:10px;\">\n    <span>\u0627\u062d\u0635\u0644 \u0639\u0644\u0649 \u0639\u0631\u0636 \u0623\u0633\u0639\u0627\u0631 \u0627\u0644\u0622\u0646!<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-solid\"  id=\"row-2008334123\">\n\n\n\t<div class=\"col medium-1 small-12 large-1\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-10 small-12 large-10\"  >\n\t\t<div class=\"col-inner\" style=\"background-color:rgba(104, 246, 247, 0.18);\" >\n\t\t\t\n\t\t\t\n\n<div style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>\u0645\u0639\u062a\u0645\u062f \u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0641\u064a \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u064a\u0627\u062a \u0648\u0645\u062d\u0644\u0627\u062a \u0627\u0644\u0628\u064a\u0639 \u0628\u0627\u0644\u062a\u062c\u0632\u0626\u0629 \u0648\u0627\u0644\u0645\u0643\u0627\u062a\u0628 \u0648\u0627\u0644\u0645\u062f\u0627\u0631\u0633 \u0648\u0627\u0644\u0645\u0646\u0632\u0644<\/strong><\/span><\/div>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">\u0627\u0644\u0623\u062d\u062c\u0627\u0645 \u0645\u062a\u0648\u0641\u0631\u0629 \u0641\u064a 50 \u0645\u0644\u060c 100 \u0645\u0644\u060c 500 \u0645\u0644\u060c 1 \u0644\u062a\u0631\u060c 5 \u0644\u062a\u0631 \u064810 \u0644\u062a\u0631. \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u062a\u0639\u0628\u0626\u0629 \u0648\u0627\u0644\u062a\u063a\u0644\u064a\u0641 \u0645\u062a\u0648\u0641\u0631\u0629 \u0641\u064a \u0639\u0628\u0648\u0627\u062a \u0628\u063a\u0637\u0627\u0621 \u0642\u0644\u0627\u0628 \u0648\u0645\u0636\u062e\u0629 \u0648\u0631\u0630\u0627\u0630 \u0631\u0630\u0627\u0630. \u0623\u0634\u0643\u0627\u0644 \u0633\u0627\u0626\u0644\u0629 \u0648\u062c\u0644.  <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-1 small-12 large-1\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"color:rgb(43, 42, 239);\"><i class=\"icon-angle-down\" ><\/i>\u0645\u0637\u0647\u0631 \u0627\u0644\u0623\u0633\u0637\u062d<\/span><b><\/b><\/h2><\/div>\n\n<div class=\"row\"  id=\"row-1846334631\">\n\n\n\t<div class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_589236755\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1020\" height=\"638\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/06\/Surface-Disinfectant-1.jpg?fit=1020%2C638&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"surface disinfectant\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/06\/Surface-Disinfectant-1.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/06\/Surface-Disinfectant-1.jpg?resize=640%2C400&amp;ssl=1 640w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/06\/Surface-Disinfectant-1.jpg?resize=1280%2C800&amp;ssl=1 1280w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/06\/Surface-Disinfectant-1.jpg?resize=768%2C480&amp;ssl=1 768w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/06\/Surface-Disinfectant-1.jpg?resize=1536%2C960&amp;ssl=1 1536w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/06\/Surface-Disinfectant-1.jpg?resize=600%2C375&amp;ssl=1 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style scope=\"scope\">\n\n#image_589236755 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1802498609\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"638\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Surface-Disinfectant-3.jpg?fit=1020%2C638&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"Surface Disinfectant\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Surface-Disinfectant-3.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Surface-Disinfectant-3.jpg?resize=640%2C400&amp;ssl=1 640w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Surface-Disinfectant-3.jpg?resize=1280%2C800&amp;ssl=1 1280w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Surface-Disinfectant-3.jpg?resize=768%2C480&amp;ssl=1 768w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Surface-Disinfectant-3.jpg?resize=1536%2C960&amp;ssl=1 1536w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Surface-Disinfectant-3.jpg?resize=600%2C375&amp;ssl=1 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style scope=\"scope\">\n\n#image_1802498609 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"color: #000000;\">\u0646\u0642\u0648\u0645 \u0623\u064a\u0636\u064b\u0627 \u0628\u062a\u0635\u0646\u064a\u0639 \u0645\u0637\u0647\u0631 \u0627\u0644\u0623\u0633\u0637\u062d \u0648\u0645\u0637\u0647\u0631 \u0627\u0644\u062a\u0639\u0641\u064a\u0631 \u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u062f\u0627\u062e\u0644\u064a \u0648\u0627\u0644\u062e\u0627\u0631\u062c\u064a. \u062a\u0645 \u0627\u062e\u062a\u0628\u0627\u0631 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0645\u0639\u0645\u0644\u064a\u0627\u064b \u0648\u062b\u0628\u062a \u0623\u0646\u0647\u0627 <strong>\u062a\u0642\u062a\u0644 99.99% \u0645\u0646 \u0627\u0644\u062c\u0631\u0627\u062b\u064a\u0645.<\/strong> \u062a\u0642\u0631\u064a\u0631 SDS \u0645\u062a\u0627\u062d.   <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"color:rgb(43, 42, 239);\"><i class=\"icon-angle-down\" ><\/i>\u0645\u064f\u0635\u0646\u0650\u0651\u0639 GMP<\/span><b><\/b><\/h2><\/div>\n\n<div class=\"row\"  id=\"row-453031464\">\n\n\n\t<div class=\"col medium-1 small-12 large-1\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-10 small-12 large-10\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">\u0634\u0631\u0643\u0629 ISD Meditech Sdn Bhd \u0647\u064a \u0634\u0631\u0643\u0629 \u0645\u0635\u0646\u0639\u0629 \u062d\u0627\u0635\u0644\u0629 \u0639\u0644\u0649 \u0634\u0647\u0627\u062f\u0629 <strong>\u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u062c\u064a\u062f\u0629 (GMP)<\/strong>. \u0645\u0648\u0632\u0639\u0646\u0627 \u0627\u0644\u0645\u0639\u062a\u0645\u062f \u0644\u0644\u0645\u0628\u064a\u0639\u0627\u062a &#8211; Tele-Paper Sdn Bhd (ISO 9001 \u0648ISO 13485) \u0647\u0648 \u0627\u0644\u0645\u0648\u0632\u0639 \u0627\u0644\u0648\u062d\u064a\u062f \u0627\u0644\u0631\u0627\u0626\u062f \u0644\u0645\u0637\u0647\u0631\u0627\u062a \u0627\u0644\u064a\u062f\u064a\u0646 Sky Gel \u0648Sonogel \u0644\u0623\u0643\u062b\u0631 \u0645\u0646 10 \u0633\u0646\u0648\u0627\u062a. \u0645\u0639 \u0632\u064a\u0627\u062f\u0629 \u0627\u0644\u0637\u0644\u0628 \u0641\u064a \u0627\u0644\u0623\u0633\u0648\u0627\u0642 \u0627\u0644\u062e\u0627\u0631\u062c\u064a\u0629\u060c \u0642\u0645\u0646\u0627 \u0628\u062a\u0648\u0633\u064a\u0639 \u0623\u0633\u0648\u0627\u0642\u0646\u0627 \u0627\u0644\u062a\u0635\u062f\u064a\u0631\u064a\u0629 \u0625\u0644\u0649 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0628\u0644\u062f\u0627\u0646 \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u0629 \u0648\u0647\u0648\u0646\u062c \u0643\u0648\u0646\u062c \u0648\u0627\u0644\u0648\u0644\u0627\u064a\u0627\u062a \u0627\u0644\u0645\u062a\u062d\u062f\u0629 \u0648\u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637.    <\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-1 small-12 large-1\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-204277991\">\n\n\n\t<div class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_538345072\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?fit=800%2C800&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"Large Quantity Hand Sanitizer\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?resize=280%2C280&amp;ssl=1 280w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/Large-Quantity-Tele.jpg?resize=100%2C100&amp;ssl=1 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style scope=\"scope\">\n\n#image_538345072 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col hide-for-small medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover hide-for-small x md-x lg-x y md-y lg-y\" id=\"image_2097178707\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?fit=800%2C800&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"why choose sky gel\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?resize=280%2C280&amp;ssl=1 280w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/08\/1-01-1.jpg?resize=100%2C100&amp;ssl=1 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style scope=\"scope\">\n\n#image_2097178707 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover hide-for-small x md-x lg-x y md-y lg-y\" id=\"image_178124755\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/0-04.jpg?fit=768%2C768&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"GMP Certification\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/0-04.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/0-04.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/0-04.jpg?resize=280%2C280&amp;ssl=1 280w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/0-04.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/0-04.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/0-04.jpg?resize=100%2C100&amp;ssl=1 100w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style scope=\"scope\">\n\n#image_178124755 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b><\/b><span class=\"section-title-main\" style=\"color:rgb(43, 42, 239);\"><i class=\"icon-angle-down\" ><\/i>\u0627\u0644\u0634\u062d\u0646 \u0627\u0644\u0645\u0628\u0627\u0634\u0631 \u0645\u0646 \u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0645\u0635\u0646\u0639\u0629<\/span><b><\/b><\/h2><\/div>\n\n<div class=\"row\"  id=\"row-706499087\">\n\n\n\t<div class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_878695558\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/95268858_3543508019009390_7140591693211893760_n.jpg?fit=600%2C800&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"warehouse product\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/95268858_3543508019009390_7140591693211893760_n.jpg?w=684&amp;ssl=1 684w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/95268858_3543508019009390_7140591693211893760_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/95268858_3543508019009390_7140591693211893760_n.jpg?resize=600%2C800&amp;ssl=1 600w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style scope=\"scope\">\n\n#image_878695558 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_193024530\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/95763609_3543508079009384_2714556864514752512_n.jpg?fit=600%2C800&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"warehouse product\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/95763609_3543508079009384_2714556864514752512_n.jpg?w=684&amp;ssl=1 684w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/95763609_3543508079009384_2714556864514752512_n.jpg?resize=300%2C400&amp;ssl=1 300w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/95763609_3543508079009384_2714556864514752512_n.jpg?resize=600%2C800&amp;ssl=1 600w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style scope=\"scope\">\n\n#image_193024530 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1320526321\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"765\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-17-at-1.26.24-PM.jpeg?fit=1020%2C765&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"warehouse product\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-17-at-1.26.24-PM.jpeg?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-17-at-1.26.24-PM.jpeg?resize=533%2C400&amp;ssl=1 533w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-17-at-1.26.24-PM.jpeg?resize=1067%2C800&amp;ssl=1 1067w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-17-at-1.26.24-PM.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/05\/WhatsApp-Image-2020-05-17-at-1.26.24-PM.jpeg?resize=600%2C450&amp;ssl=1 600w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style scope=\"scope\">\n\n#image_1320526321 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p>\u0645\u0639\u0642\u0645 \u0627\u0644\u064a\u062f\u064a\u0646 \u0645\u0639\u0628\u0623 \u0628\u0625\u062d\u0643\u0627\u0645 \u0648\u062c\u0627\u0647\u0632 \u0644\u0644\u0634\u062d\u0646.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-904071106\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style scope=\"scope\">\n\n#gap-904071106 {\n  padding-top: 0px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h2 id=\"contact_form_sg_id\" style=\"text-align: center;\"><span style=\"color: #000000;\">\u0627\u062d\u0635\u0644 \u0639\u0644\u0649 \u0639\u0631\u0636 \u0623\u0633\u0639\u0627\u0631 \u0627\u0644\u0622\u0646!<\/span><\/h2>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">\u0627\u0645\u0644\u0623 \u0646\u0645\u0648\u0630\u062c \u0637\u0644\u0628 \u0639\u0631\u0636 \u0627\u0644\u0623\u0633\u0639\u0627\u0631 \u0623\u062f\u0646\u0627\u0647 \u0648\u0633\u0646\u0639\u0627\u0648\u062f \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0628\u0643 \u0641\u064a \u063a\u0636\u0648\u0646 \u064a\u0648\u0645 \u0639\u0645\u0644 \u0648\u0627\u062d\u062f<\/span><\/p>\n<div class=\"row\"  id=\"row-928458545\">\n\n\n\t<div class=\"col contact-sanitizer medium-7 small-12 large-7\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3545-o1\" lang=\"ar\" dir=\"rtl\" data-wpcf7-id=\"3545\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/3539#wpcf7-f3545-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0646\u0645\u0648\u0630\u062c \u0627\u0644\u0627\u062a\u0635\u0627\u0644\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3545\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ar\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3545-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> \u0627\u0633\u0645\u0643<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> \u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> \u0631\u0642\u0645 \u0627\u0644\u0627\u062a\u0635\u0627\u0644<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-number\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-number\" \/><\/span> <\/label>\n<\/p>\n<p><label> \u0627\u0644\u0634\u0631\u0643\u0629 (\u0625\u0646 \u0648\u062c\u062f\u062a)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span> <\/label>\n<\/p>\n<p><label>\u0627\u0644\u0628\u0644\u062f<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-country\" \/><\/span><br \/>\n<\/label>\n<\/p>\n<p><label> \u0631\u0633\u0627\u0644\u062a\u0643 (\u064a\u064f\u0631\u062c\u0649 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u0631 \u0639\u0644\u0649 100 \u0643\u0644\u0645\u0629 \u0641\u0642\u0637)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"\u0625\u0631\u0633\u0627\u0644\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n\t<div class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-726512845\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style scope=\"scope\">\n\n#gap-726512845 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">\u0627\u062a\u0635\u0644 \u0628\u0646\u0627 \u0627\u0644\u0622\u0646 \u0639\u0628\u0631 \u0627\u0644\u0648\u0627\u062a\u0633\u0627\u0628 +6017-5124147+<\/span><\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1138178073\">\n\t\t<a class=\"\" href=\"https:\/\/wa.link\/3h66vi\"  >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"797\" height=\"800\" src=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?fit=797%2C800&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"whatsapp-logo\" srcset=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?w=2100&amp;ssl=1 2100w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=398%2C400&amp;ssl=1 398w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=797%2C800&amp;ssl=1 797w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=280%2C280&amp;ssl=1 280w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=768%2C771&amp;ssl=1 768w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=1529%2C1536&amp;ssl=1 1529w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=2039%2C2048&amp;ssl=1 2039w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=600%2C603&amp;ssl=1 600w, https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/07\/whatsapp-logo-1-1.png?resize=100%2C100&amp;ssl=1 100w\" sizes=\"(max-width: 797px) 100vw, 797px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style scope=\"scope\">\n\n#image_1138178073 {\n  width: 28%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\n\t\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u064f\u0635\u0646\u0651\u0639 \u0645\u0639\u0642\u0645 \u0627\u0644\u064a\u062f\u064a\u0646 \u0644 \u062e\u0628\u0631\u0629 10 \u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0644 \u0645\u0633\u062c\u0644 \u0644\u062f\u0649 \u0648\u0632\u0627\u0631\u0629 \u0627\u0644\u0635\u062d\u0629 \u0645\u0639\u0642\u0645 \u0644\u0644\u064a\u062f\u064a\u0646 \u0645\u0646 \u0641\u0626\u0629 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u064a\u0627\u062a. \u0627\u0644\u062a\u0648\u0635\u064a\u0644 \u0645\u0646 \u0627\u0644\u0628\u0627\u0628 \u0625\u0644\u0649 \u0627\u0644\u0628\u0627\u0628 \u0645\u062c\u0627\u0646\u064b\u0627 \u0625\u0644\u0649 \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u0629 \u0639\u0646\u062f \u0627\u0644\u0634\u0631\u0627\u0621 \u0628\u0642\u064a\u0645\u0629 \u062a\u0632\u064a\u062f \u0639\u0646 1500 \u062f\u0648\u0644\u0627\u0631 \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u064a \u0623\u0648 100 \u062f\u0648\u0644\u0627\u0631 \u0623\u0645\u0631\u064a\u0643\u064a \u0627\u062d\u0635\u0644 \u0639\u0644\u0649 \u0639\u0631\u0636 \u0623\u0633\u0639\u0627\u0631 \u0627\u0644\u0622\u0646! \u0627\u0645\u0644\u0623 \u0646\u0645\u0648\u0630\u062c \u0637\u0644\u0628 \u0639\u0631\u0636 \u0627\u0644\u0623\u0633\u0639\u0627\u0631 \u0623\u062f\u0646\u0627\u0647 \u0648\u0633\u0646\u0639\u0627\u0648\u062f \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0628\u0643 \u0641\u064a \u063a\u0636\u0648\u0646 [&#8230;]\n","protected":false},"author":2,"featured_media":3120,"parent":3532,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank-landingpage.php","meta":{"footnotes":""},"class_list":["post-3539","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0645\u0635\u0646\u0639\u0629 \u0644\u0645\u0637\u0647\u0631 \u0627\u0644\u064a\u062f\u064a\u0646 l \u0645\u0639\u062a\u0645\u062f \u0645\u0646 KKM ISD Meditech<\/title>\n<meta name=\"description\" content=\"\u0645\u064f\u0635\u0646\u0650\u0651\u0639 \u0645\u0639\u0642\u0645\u0627\u062a \u064a\u062f\u0648\u064a\u0629 \u0631\u0627\u0633\u062e\u0629 \u0628\u062e\u0628\u0631\u0629 \u062a\u0632\u064a\u062f \u0639\u0646 10 \u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u062c\u064a\u062f\u0629 \u0648\u0627\u0644\u0645\u0637\u0647\u0631\u0627\u062a \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0629 \u0645\u0646 KKM \u0642\u0645 \u0628\u0632\u064a\u0627\u0631\u062a\u0646\u0627 \u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0645\u0632\u064a\u062f.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0645\u0635\u0646\u0639\u0629 \u0644\u0645\u0637\u0647\u0631 \u0627\u0644\u064a\u062f\u064a\u0646 l \u0645\u0639\u062a\u0645\u062f \u0645\u0646 KKM ISD Meditech\" \/>\n<meta property=\"og:description\" content=\"\u0645\u064f\u0635\u0646\u0650\u0651\u0639 \u0645\u0639\u0642\u0645\u0627\u062a \u064a\u062f\u0648\u064a\u0629 \u0631\u0627\u0633\u062e\u0629 \u0628\u062e\u0628\u0631\u0629 \u062a\u0632\u064a\u062f \u0639\u0646 10 \u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u062c\u064a\u062f\u0629 \u0648\u0627\u0644\u0645\u0637\u0647\u0631\u0627\u062a \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0629 \u0645\u0646 KKM \u0642\u0645 \u0628\u0632\u064a\u0627\u0631\u062a\u0646\u0627 \u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0645\u0632\u064a\u062f.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/\" \/>\n<meta property=\"og:site_name\" content=\"ISD Meditech Sdn. Bhd.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063622265926\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T06:53:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/03\/cropped-ISD-logo.jpg?fit=512%2C512&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u062f\u0642\u064a\u0642\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\\\/\",\"url\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\\\/\",\"name\":\"\u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0645\u0635\u0646\u0639\u0629 \u0644\u0645\u0637\u0647\u0631 \u0627\u0644\u064a\u062f\u064a\u0646 l \u0645\u0639\u062a\u0645\u062f \u0645\u0646 KKM ISD Meditech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/isdmeditech.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-ISD-logo.jpg?fit=512%2C512&ssl=1\",\"datePublished\":\"2020-07-25T09:43:56+00:00\",\"dateModified\":\"2024-12-02T06:53:03+00:00\",\"description\":\"\u0645\u064f\u0635\u0646\u0650\u0651\u0639 \u0645\u0639\u0642\u0645\u0627\u062a \u064a\u062f\u0648\u064a\u0629 \u0631\u0627\u0633\u062e\u0629 \u0628\u062e\u0628\u0631\u0629 \u062a\u0632\u064a\u062f \u0639\u0646 10 \u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u062c\u064a\u062f\u0629 \u0648\u0627\u0644\u0645\u0637\u0647\u0631\u0627\u062a \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0629 \u0645\u0646 KKM \u0642\u0645 \u0628\u0632\u064a\u0627\u0631\u062a\u0646\u0627 \u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0645\u0632\u064a\u062f.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/isdmeditech.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-ISD-logo.jpg?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/isdmeditech.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-ISD-logo.jpg?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629\",\"item\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0645\u0639\u0642\u0645 \u0627\u0644\u064a\u062f\u064a\u0646 _ \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u0629\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/\",\"name\":\"ISD Meditech Sdn. Bhd.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/#organization\",\"name\":\"ISD Meditech Sdn. Bhd.\",\"url\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.isdmeditech.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-ISD-logo-1.jpg?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.isdmeditech.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-ISD-logo-1.jpg?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"ISD Meditech Sdn. Bhd.\"},\"image\":{\"@id\":\"https:\\\/\\\/isdmeditech.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063622265926\",\"https:\\\/\\\/www.instagram.com\\\/isdmeditech.sdn.bhd\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0645\u0635\u0646\u0639\u0629 \u0644\u0645\u0637\u0647\u0631 \u0627\u0644\u064a\u062f\u064a\u0646 l \u0645\u0639\u062a\u0645\u062f \u0645\u0646 KKM ISD Meditech","description":"\u0645\u064f\u0635\u0646\u0650\u0651\u0639 \u0645\u0639\u0642\u0645\u0627\u062a \u064a\u062f\u0648\u064a\u0629 \u0631\u0627\u0633\u062e\u0629 \u0628\u062e\u0628\u0631\u0629 \u062a\u0632\u064a\u062f \u0639\u0646 10 \u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u062c\u064a\u062f\u0629 \u0648\u0627\u0644\u0645\u0637\u0647\u0631\u0627\u062a \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0629 \u0645\u0646 KKM \u0642\u0645 \u0628\u0632\u064a\u0627\u0631\u062a\u0646\u0627 \u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0645\u0632\u064a\u062f.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0645\u0635\u0646\u0639\u0629 \u0644\u0645\u0637\u0647\u0631 \u0627\u0644\u064a\u062f\u064a\u0646 l \u0645\u0639\u062a\u0645\u062f \u0645\u0646 KKM ISD Meditech","og_description":"\u0645\u064f\u0635\u0646\u0650\u0651\u0639 \u0645\u0639\u0642\u0645\u0627\u062a \u064a\u062f\u0648\u064a\u0629 \u0631\u0627\u0633\u062e\u0629 \u0628\u062e\u0628\u0631\u0629 \u062a\u0632\u064a\u062f \u0639\u0646 10 \u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u062c\u064a\u062f\u0629 \u0648\u0627\u0644\u0645\u0637\u0647\u0631\u0627\u062a \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0629 \u0645\u0646 KKM \u0642\u0645 \u0628\u0632\u064a\u0627\u0631\u062a\u0646\u0627 \u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0645\u0632\u064a\u062f.","og_url":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/","og_site_name":"ISD Meditech Sdn. Bhd.","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063622265926","article_modified_time":"2024-12-02T06:53:03+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/03\/cropped-ISD-logo.jpg?fit=512%2C512&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"1 \u062f\u0642\u064a\u0642\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/","url":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/","name":"\u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0645\u0635\u0646\u0639\u0629 \u0644\u0645\u0637\u0647\u0631 \u0627\u0644\u064a\u062f\u064a\u0646 l \u0645\u0639\u062a\u0645\u062f \u0645\u0646 KKM ISD Meditech","isPartOf":{"@id":"https:\/\/isdmeditech.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/#primaryimage"},"image":{"@id":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/03\/cropped-ISD-logo.jpg?fit=512%2C512&ssl=1","datePublished":"2020-07-25T09:43:56+00:00","dateModified":"2024-12-02T06:53:03+00:00","description":"\u0645\u064f\u0635\u0646\u0650\u0651\u0639 \u0645\u0639\u0642\u0645\u0627\u062a \u064a\u062f\u0648\u064a\u0629 \u0631\u0627\u0633\u062e\u0629 \u0628\u062e\u0628\u0631\u0629 \u062a\u0632\u064a\u062f \u0639\u0646 10 \u0633\u0646\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u062e\u0628\u0631\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0645\u0645\u0627\u0631\u0633\u0627\u062a \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u062c\u064a\u062f\u0629 \u0648\u0627\u0644\u0645\u0637\u0647\u0631\u0627\u062a \u0627\u0644\u0645\u0639\u062a\u0645\u062f\u0629 \u0645\u0646 KKM \u0642\u0645 \u0628\u0632\u064a\u0627\u0631\u062a\u0646\u0627 \u0644\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0645\u0632\u064a\u062f.","breadcrumb":{"@id":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/#primaryimage","url":"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/03\/cropped-ISD-logo.jpg?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/isdmeditech.com\/wp-content\/uploads\/2020\/03\/cropped-ISD-logo.jpg?fit=512%2C512&ssl=1","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/%d9%85%d8%b9%d9%82%d9%85-%d8%a7%d9%84%d9%8a%d8%af%d9%8a%d9%86-_-%d8%b3%d9%86%d8%ba%d8%a7%d9%81%d9%88%d8%b1%d8%a9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/isdmeditech.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629","item":"https:\/\/isdmeditech.com\/ar\/%d8%a7%d9%84%d8%b5%d9%81%d8%ad%d8%a9-%d8%a7%d9%84%d8%b1%d8%a6%d9%8a%d8%b3%d9%8a%d8%a9\/"},{"@type":"ListItem","position":3,"name":"\u0645\u0639\u0642\u0645 \u0627\u0644\u064a\u062f\u064a\u0646 _ \u0633\u0646\u063a\u0627\u0641\u0648\u0631\u0629"}]},{"@type":"WebSite","@id":"https:\/\/isdmeditech.com\/ar\/#website","url":"https:\/\/isdmeditech.com\/ar\/","name":"ISD Meditech Sdn. Bhd.","description":"","publisher":{"@id":"https:\/\/isdmeditech.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/isdmeditech.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/isdmeditech.com\/ar\/#organization","name":"ISD Meditech Sdn. Bhd.","url":"https:\/\/isdmeditech.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/isdmeditech.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.isdmeditech.com\/wp-content\/uploads\/2020\/03\/cropped-ISD-logo-1.jpg?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.isdmeditech.com\/wp-content\/uploads\/2020\/03\/cropped-ISD-logo-1.jpg?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"ISD Meditech Sdn. Bhd."},"image":{"@id":"https:\/\/isdmeditech.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063622265926","https:\/\/www.instagram.com\/isdmeditech.sdn.bhd\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/pages\/3539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/comments?post=3539"}],"version-history":[{"count":1,"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/pages\/3539\/revisions"}],"predecessor-version":[{"id":3540,"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/pages\/3539\/revisions\/3540"}],"up":[{"embeddable":true,"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/pages\/3532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/media\/3120"}],"wp:attachment":[{"href":"https:\/\/isdmeditech.com\/ar\/wp-json\/wp\/v2\/media?parent=3539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}